{"id":364,"count":1,"description":"","link":"https:\/\/www.swoop-patagonia.com\/blog\/tag\/brush-lake\/","name":"Brush Lake","slug":"brush-lake","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brush Lake Archives - Swoop Patagonia Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.swoop-patagonia.com\/blog\/tag\/brush-lake\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brush Lake Archives - Swoop Patagonia Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.swoop-patagonia.com\/blog\/tag\/brush-lake\/\" \/>\n<meta property=\"og:site_name\" content=\"Swoop Patagonia Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/tag\\\/brush-lake\\\/\",\"url\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/tag\\\/brush-lake\\\/\",\"name\":\"Brush Lake Archives - Swoop Patagonia Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/tag\\\/brush-lake\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/tag\\\/brush-lake\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brush Lake\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/\",\"name\":\"Swoop Patagonia Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/#organization\",\"name\":\"Swoop Patagonia Blog\",\"url\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/swoop-patagonia-logo-blog.svg\",\"contentUrl\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/swoop-patagonia-logo-blog.svg\",\"width\":1220,\"height\":108,\"caption\":\"Swoop Patagonia Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.swoop-patagonia.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brush Lake Archives - Swoop Patagonia Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.swoop-patagonia.com\/blog\/tag\/brush-lake\/","og_locale":"en_GB","og_type":"article","og_title":"Brush Lake Archives - Swoop Patagonia Blog","og_url":"https:\/\/www.swoop-patagonia.com\/blog\/tag\/brush-lake\/","og_site_name":"Swoop Patagonia Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.swoop-patagonia.com\/blog\/tag\/brush-lake\/","url":"https:\/\/www.swoop-patagonia.com\/blog\/tag\/brush-lake\/","name":"Brush Lake Archives - Swoop Patagonia Blog","isPartOf":{"@id":"https:\/\/www.swoop-patagonia.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.swoop-patagonia.com\/blog\/tag\/brush-lake\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.swoop-patagonia.com\/blog\/tag\/brush-lake\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.swoop-patagonia.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Brush Lake"}]},{"@type":"WebSite","@id":"https:\/\/www.swoop-patagonia.com\/blog\/#website","url":"https:\/\/www.swoop-patagonia.com\/blog\/","name":"Swoop Patagonia Blog","description":"","publisher":{"@id":"https:\/\/www.swoop-patagonia.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.swoop-patagonia.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.swoop-patagonia.com\/blog\/#organization","name":"Swoop Patagonia Blog","url":"https:\/\/www.swoop-patagonia.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.swoop-patagonia.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.swoop-patagonia.com\/blog\/wp-content\/uploads\/2024\/12\/swoop-patagonia-logo-blog.svg","contentUrl":"https:\/\/www.swoop-patagonia.com\/blog\/wp-content\/uploads\/2024\/12\/swoop-patagonia-logo-blog.svg","width":1220,"height":108,"caption":"Swoop Patagonia Blog"},"image":{"@id":"https:\/\/www.swoop-patagonia.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.swoop-patagonia.com\/blog\/wp-json\/wp\/v2\/tags\/364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.swoop-patagonia.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.swoop-patagonia.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.swoop-patagonia.com\/blog\/wp-json\/wp\/v2\/posts?tags=364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}